{"id":3979,"date":"2022-11-29T14:07:38","date_gmt":"2022-11-29T13:07:38","guid":{"rendered":"https:\/\/tischlerei-lanser.at\/?p=3979"},"modified":"2022-12-20T09:57:57","modified_gmt":"2022-12-20T08:57:57","slug":"lanser-lienz-mit-haestens-store-wieder-geoeffnet","status":"publish","type":"post","link":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/","title":{"rendered":"Lanser Lienz mit H\u00e4stens Store wieder ge\u00f6ffnet"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lanser Lienz nach Umbau wieder ge\u00f6ffnet &#8211; Tischlerei Lanser<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lanser Lienz nach Umbau wieder ge\u00f6ffnet &#8211; Tischlerei Lanser\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/\" \/>\n<meta property=\"og:site_name\" content=\"Tischlerei Lanser\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TischlereiLanser\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T13:07:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-20T08:57:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Showroom-Lanser-Lienz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lanser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"lanser\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/\"},\"author\":{\"name\":\"lanser\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/#\\\/schema\\\/person\\\/65ec986a3544f6c4ff1eda8d58cec0c9\"},\"headline\":\"Lanser Lienz mit H\u00e4stens Store wieder ge\u00f6ffnet\",\"datePublished\":\"2022-11-29T13:07:38+00:00\",\"dateModified\":\"2022-12-20T08:57:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/\"},\"wordCount\":10,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tischlerei-lanser.at\\\/wp-content\\\/uploads\\\/Showroom-Lanser-Lienz.jpg\",\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tischlerei-lanser.at\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/\",\"url\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/\",\"name\":\"Lanser Lienz nach Umbau wieder ge\u00f6ffnet &#8211; Tischlerei Lanser\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tischlerei-lanser.at\\\/wp-content\\\/uploads\\\/Showroom-Lanser-Lienz.jpg\",\"datePublished\":\"2022-11-29T13:07:38+00:00\",\"dateModified\":\"2022-12-20T08:57:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tischlerei-lanser.at\\\/wp-content\\\/uploads\\\/Showroom-Lanser-Lienz.jpg\",\"contentUrl\":\"https:\\\/\\\/tischlerei-lanser.at\\\/wp-content\\\/uploads\\\/Showroom-Lanser-Lienz.jpg\",\"width\":1920,\"height\":1279,\"caption\":\"Tischlerei Lanser Showroom Lienz, Osttirol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/2022\\\/11\\\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lanser Lienz mit H\u00e4stens Store wieder ge\u00f6ffnet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/\",\"name\":\"Tischlerei Lanser\",\"description\":\"Wo Natur erhalten wird.\",\"publisher\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/#organization\",\"name\":\"Tischlerei Lanser\",\"url\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tischlerei-lanser.at\\\/wp-content\\\/uploads\\\/Lanser_Logo_Jahreszahl.jpg\",\"contentUrl\":\"https:\\\/\\\/tischlerei-lanser.at\\\/wp-content\\\/uploads\\\/Lanser_Logo_Jahreszahl.jpg\",\"width\":1920,\"height\":1015,\"caption\":\"Tischlerei Lanser\"},\"image\":{\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TischlereiLanser\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tischlerei_lanser\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10006620\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tischlerei-lanser.at\\\/#\\\/schema\\\/person\\\/65ec986a3544f6c4ff1eda8d58cec0c9\",\"name\":\"lanser\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lanser Lienz nach Umbau wieder ge\u00f6ffnet &#8211; Tischlerei Lanser","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/","og_locale":"en_US","og_type":"article","og_title":"Lanser Lienz nach Umbau wieder ge\u00f6ffnet &#8211; Tischlerei Lanser","og_url":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/","og_site_name":"Tischlerei Lanser","article_publisher":"https:\/\/www.facebook.com\/TischlereiLanser\/","article_published_time":"2022-11-29T13:07:38+00:00","article_modified_time":"2022-12-20T08:57:57+00:00","og_image":[{"width":1920,"height":1279,"url":"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Showroom-Lanser-Lienz.jpg","type":"image\/jpeg"}],"author":"lanser","twitter_card":"summary_large_image","twitter_misc":{"Written by":"lanser"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tischlerei-lanser.at\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#article","isPartOf":{"@id":"https:\/\/tischlerei-lanser.at\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/"},"author":{"name":"lanser","@id":"https:\/\/tischlerei-lanser.at\/#\/schema\/person\/65ec986a3544f6c4ff1eda8d58cec0c9"},"headline":"Lanser Lienz mit H\u00e4stens Store wieder ge\u00f6ffnet","datePublished":"2022-11-29T13:07:38+00:00","dateModified":"2022-12-20T08:57:57+00:00","mainEntityOfPage":{"@id":"https:\/\/tischlerei-lanser.at\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/tischlerei-lanser.at\/#organization"},"image":{"@id":"https:\/\/tischlerei-lanser.at\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#primaryimage"},"thumbnailUrl":"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Showroom-Lanser-Lienz.jpg","articleSection":["Allgemein"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tischlerei-lanser.at\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/","url":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/","name":"Lanser Lienz nach Umbau wieder ge\u00f6ffnet &#8211; Tischlerei Lanser","isPartOf":{"@id":"https:\/\/tischlerei-lanser.at\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#primaryimage"},"image":{"@id":"https:\/\/tischlerei-lanser.at\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#primaryimage"},"thumbnailUrl":"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Showroom-Lanser-Lienz.jpg","datePublished":"2022-11-29T13:07:38+00:00","dateModified":"2022-12-20T08:57:57+00:00","breadcrumb":{"@id":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#primaryimage","url":"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Showroom-Lanser-Lienz.jpg","contentUrl":"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Showroom-Lanser-Lienz.jpg","width":1920,"height":1279,"caption":"Tischlerei Lanser Showroom Lienz, Osttirol"},{"@type":"BreadcrumbList","@id":"https:\/\/tischlerei-lanser.at\/en\/2022\/11\/lanser-lienz-mit-haestens-store-wieder-geoeffnet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tischlerei-lanser.at\/en\/"},{"@type":"ListItem","position":2,"name":"Lanser Lienz mit H\u00e4stens Store wieder ge\u00f6ffnet"}]},{"@type":"WebSite","@id":"https:\/\/tischlerei-lanser.at\/en\/#website","url":"https:\/\/tischlerei-lanser.at\/en\/","name":"Tischlerei Lanser","description":"Wo Natur erhalten wird.","publisher":{"@id":"https:\/\/tischlerei-lanser.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tischlerei-lanser.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tischlerei-lanser.at\/en\/#organization","name":"Tischlerei Lanser","url":"https:\/\/tischlerei-lanser.at\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tischlerei-lanser.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Lanser_Logo_Jahreszahl.jpg","contentUrl":"https:\/\/tischlerei-lanser.at\/wp-content\/uploads\/Lanser_Logo_Jahreszahl.jpg","width":1920,"height":1015,"caption":"Tischlerei Lanser"},"image":{"@id":"https:\/\/tischlerei-lanser.at\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TischlereiLanser\/","https:\/\/www.instagram.com\/tischlerei_lanser\/","https:\/\/www.linkedin.com\/company\/10006620"]},{"@type":"Person","@id":"https:\/\/tischlerei-lanser.at\/#\/schema\/person\/65ec986a3544f6c4ff1eda8d58cec0c9","name":"lanser"}]}},"_links":{"self":[{"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/posts\/3979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/comments?post=3979"}],"version-history":[{"count":23,"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/posts\/3979\/revisions"}],"predecessor-version":[{"id":4047,"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/posts\/3979\/revisions\/4047"}],"wp:attachment":[{"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/media?parent=3979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/categories?post=3979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tischlerei-lanser.at\/en\/wp-json\/wp\/v2\/tags?post=3979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}